{"id":1064,"date":"2022-11-24T20:26:33","date_gmt":"2022-11-24T18:26:33","guid":{"rendered":"https:\/\/clicksgroup.co.za\/iar2025\/?page_id=1064"},"modified":"2025-11-13T13:18:15","modified_gmt":"2025-11-13T11:18:15","slug":"bertina-engelbrecht-2","status":"publish","type":"page","link":"https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/","title":{"rendered":"Bertina Engelbrecht"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-cv.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1064","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bertina Engelbrecht - Clicks IAR 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bertina Engelbrecht - Clicks IAR 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Clicks IAR 2025\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T11:18:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/bertina-engelbrecht-2\\\/\",\"url\":\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/bertina-engelbrecht-2\\\/\",\"name\":\"Bertina Engelbrecht - Clicks IAR 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/#website\"},\"datePublished\":\"2022-11-24T18:26:33+00:00\",\"dateModified\":\"2025-11-13T11:18:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/bertina-engelbrecht-2\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/bertina-engelbrecht-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/bertina-engelbrecht-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bertina Engelbrecht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/#website\",\"url\":\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/\",\"name\":\"Clicks IAR 2025\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clicksgroup.co.za\\\/iar2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bertina Engelbrecht - Clicks IAR 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/","og_locale":"en_US","og_type":"article","og_title":"Bertina Engelbrecht - Clicks IAR 2025","og_url":"https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/","og_site_name":"Clicks IAR 2025","article_modified_time":"2025-11-13T11:18:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/","url":"https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/","name":"Bertina Engelbrecht - Clicks IAR 2025","isPartOf":{"@id":"https:\/\/clicksgroup.co.za\/iar2025\/#website"},"datePublished":"2022-11-24T18:26:33+00:00","dateModified":"2025-11-13T11:18:15+00:00","breadcrumb":{"@id":"https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/#breadcrumb"},"inLanguage":"en-ZA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clicksgroup.co.za\/iar2025\/bertina-engelbrecht-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/clicksgroup.co.za\/iar2025\/"},{"@type":"ListItem","position":2,"name":"Bertina Engelbrecht"}]},{"@type":"WebSite","@id":"https:\/\/clicksgroup.co.za\/iar2025\/#website","url":"https:\/\/clicksgroup.co.za\/iar2025\/","name":"Clicks IAR 2025","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clicksgroup.co.za\/iar2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"}]}},"_links":{"self":[{"href":"https:\/\/clicksgroup.co.za\/iar2025\/wp-json\/wp\/v2\/pages\/1064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clicksgroup.co.za\/iar2025\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clicksgroup.co.za\/iar2025\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clicksgroup.co.za\/iar2025\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/clicksgroup.co.za\/iar2025\/wp-json\/wp\/v2\/comments?post=1064"}],"version-history":[{"count":11,"href":"https:\/\/clicksgroup.co.za\/iar2025\/wp-json\/wp\/v2\/pages\/1064\/revisions"}],"predecessor-version":[{"id":2937,"href":"https:\/\/clicksgroup.co.za\/iar2025\/wp-json\/wp\/v2\/pages\/1064\/revisions\/2937"}],"wp:attachment":[{"href":"https:\/\/clicksgroup.co.za\/iar2025\/wp-json\/wp\/v2\/media?parent=1064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}